{"id":2869484,"date":"2026-05-13T15:46:23","date_gmt":"2026-05-13T20:46:23","guid":{"rendered":"https:\/\/www.salvilaw.com\/?p=2869484"},"modified":"2026-05-20T10:30:22","modified_gmt":"2026-05-20T15:30:22","slug":"cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago","status":"publish","type":"post","link":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","title":{"rendered":"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago"},"content":{"rendered":"<p>CHICAGO (13 de mayo de 2026) \u2013 Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.<\/p>\n<p><a href=\"https:\/\/www.nbcchicago.com\/news\/local\/4-hospitalized-including-baby-after-crash-involving-police-in-chicago\/3935135\/\" target=\"_blank\" rel=\"noopener\">Seg\u00fan NBC Chicago<\/a>, el accidente ocurri\u00f3 en el lado oeste de Chicago alrededor de las 11:00 a. m. del martes 12 de mayo e involucr\u00f3 a m\u00faltiples veh\u00edculos, incluyendo una patrulla del Departamento de Polic\u00eda de Chicago (CPD). Tras la colisi\u00f3n, los servicios de emergencia trasladaron a cuatro personas a hospitales de la zona. Las autoridades confirmaron que un beb\u00e9 se encontraba entre los heridos. La investigaci\u00f3n del accidente contin\u00faa abierta.<\/p>\n<h2><b>\u00bfPor qu\u00e9 los accidentes con participaci\u00f3n policial pueden ser complejos?<\/b><\/h2>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2869522 size-large\" src=\"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex-1024x683.jpg\" alt=\"\u00bfPor qu\u00e9 los accidentes con participaci\u00f3n policial pueden ser complejos?\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex-1024x683.jpg 1024w, https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex-300x200.jpg 300w, https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex-768x512.jpg 768w, https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex-150x100.jpg 150w, https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Why-Police-Involved-Crashes-Can-Be-Complex.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n<p><span style=\"font-weight: 400;\">Las colisiones que involucran veh\u00edculos gubernamentales difieren de los accidentes de auto comunes. Estos casos pueden involucrar leyes de responsabilidad civil y defensas de inmunidad gubernamental, as\u00ed como investigaciones internas de la agencia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La ley de Illinois otorga a los agentes de polic\u00eda y otros socorristas ciertos privilegios de conducci\u00f3n al responder a emergencias, incluyendo pasar sem\u00e1foros en rojo o exceder los l\u00edmites de velocidad. Sin embargo, estos privilegios tienen una limitaci\u00f3n importante: los agentes deben operar sus veh\u00edculos con la debida consideraci\u00f3n a la seguridad p\u00fablica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estado de emergencia no elimina autom\u00e1ticamente la responsabilidad cuando la negligencia contribuye a un accidente. <\/span><a href=\"https:\/\/www.salvilaw.com\/es\/accidentes-de-auto\/responsabilidad-por-accidentes-derivados-de-persecuciones-policiales-o-vehiculares\/\"><span style=\"font-weight: 400;\">Haga clic aqu\u00ed<\/span><\/a><span style=\"font-weight: 400;\"> para obtener m\u00e1s informaci\u00f3n sobre la responsabilidad en accidentes por persecuciones policiales y qui\u00e9nes podr\u00edan ser considerados responsables.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Salvi, Schostok &amp; Pritchard maneja habitualmente casos complejos de colisiones de veh\u00edculos motorizados<\/strong> y comprende los problemas legales que pueden surgir cuando se ven involucradas entidades p\u00fablicas o veh\u00edculos de emergencia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHICAGO (13 de mayo de 2026) \u2013 Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9. Seg\u00fan NBC Chicago, el accidente ocurri\u00f3 en el lado oeste de Chicago alrededor de las 11:00 a. m. del martes 12 de mayo&#8230;<\/p>\n","protected":false},"author":21,"featured_media":2869544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[6375],"class_list":["post-2869484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-accidentes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Personas hospitalizadas en accidente con la polic\u00eda de Chicago | Salvi, Schostok &amp; Pritchard<\/title>\n<meta name=\"description\" content=\"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago\" \/>\n<meta property=\"og:description\" content=\"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvi, Schostok &amp; Pritchard P.C.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalviLaw\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T20:46:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T15:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcie Mangan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalviLaw\" \/>\n<meta name=\"twitter:site\" content=\"@SalviLaw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\"},\"author\":{\"name\":\"Marcie Mangan\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#\\\/schema\\\/person\\\/397e7f1c74e734538b0f150d958028a5\"},\"headline\":\"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago\",\"datePublished\":\"2026-05-13T20:46:23+00:00\",\"dateModified\":\"2026-05-20T15:30:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg\",\"articleSection\":[\"Noticias de accidentes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\",\"name\":\"Personas hospitalizadas en accidente con la polic\u00eda de Chicago | Salvi, Schostok & Pritchard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg\",\"datePublished\":\"2026-05-13T20:46:23+00:00\",\"dateModified\":\"2026-05-20T15:30:22+00:00\",\"description\":\"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/\",\"name\":\"Salvi, Schostok & Pritchard P.C.\",\"description\":\"Your Illinois Medical Malpractice and Personal Injury Attorneys\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/#\\\/schema\\\/person\\\/397e7f1c74e734538b0f150d958028a5\",\"name\":\"Marcie Mangan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g\",\"caption\":\"Marcie Mangan\"},\"description\":\"Marcella R. Mangan is the Marketing and Public Relations Director of Salvi, Schostok &amp; Pritchard P.C., where she is primarily responsible for overseeing the firm\u2019s media strategy, events and managing the firm\u2019s website, social media pages and legal listings. She joined the firm in 2016\u00a0as the Public Relations Manager, was promoted to Public Relations Director in 2018, and was promoted again to Marketing and PR Director in 2020. During her time with the firm, Ms. Mangan has regularly booked attorneys for segments on local news stations and planned numerous press conferences that were covered by national media outlets. In addition, she serves as host of the firm\u2019s official podcast: Beating Goliath \u2013 A Plaintiff\u2019s Pursuit of Justice. Ms. Mangan graduated from Butler University with degrees in Journalism and Public Relations and a minor in Dance. Upon graduation, she spent four years working in Top 25 market newsrooms, including WISH-TV in Indianapolis and FOX 32 in Chicago. In these roles, she made on-air appearances, managed the station\u2019s social media platforms, wrote articles for their websites, and worked on the assignment desk. A native of the south suburbs, Ms. Mangan holds memberships in the Public Relations Society of America and the Publicity Club of Chicago. ACADEMICS B.A., Butler University\u00a0(2012)\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/author\\\/mmangan\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo.png\",\"width\":266,\"height\":108,\"caption\":\"Salvi, Schostok & Pritchard P.C.\"}]}<\/script>\n<meta name=\"geo.region\" content=\"Estados Unidos (EEUU)\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Personas hospitalizadas en accidente con la polic\u00eda de Chicago | Salvi, Schostok & Pritchard","description":"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago","og_description":"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.","og_url":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","og_site_name":"Salvi, Schostok &amp; Pritchard P.C.","article_publisher":"https:\/\/www.facebook.com\/SalviLaw\/","article_published_time":"2026-05-13T20:46:23+00:00","article_modified_time":"2026-05-20T15:30:22+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago-1024x683.jpg","type":"image\/jpeg"}],"author":"Marcie Mangan","twitter_card":"summary_large_image","twitter_creator":"@SalviLaw","twitter_site":"@SalviLaw","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#article","isPartOf":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/"},"author":{"name":"Marcie Mangan","@id":"https:\/\/www.salvilaw.com\/es\/#\/schema\/person\/397e7f1c74e734538b0f150d958028a5"},"headline":"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago","datePublished":"2026-05-13T20:46:23+00:00","dateModified":"2026-05-20T15:30:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/"},"wordCount":306,"publisher":{"@id":"https:\/\/www.salvilaw.com\/es\/#organization"},"image":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg","articleSection":["Noticias de accidentes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","url":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","name":"Personas hospitalizadas en accidente con la polic\u00eda de Chicago | Salvi, Schostok & Pritchard","isPartOf":{"@id":"https:\/\/www.salvilaw.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#primaryimage"},"image":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg","datePublished":"2026-05-13T20:46:23+00:00","dateModified":"2026-05-20T15:30:22+00:00","description":"Un accidente reciente que involucr\u00f3 a un veh\u00edculo policial de Chicago dej\u00f3 a cuatro personas hospitalizadas, entre ellas un beb\u00e9.","breadcrumb":{"@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#primaryimage","url":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg","contentUrl":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg","width":2560,"height":1706,"caption":"Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.salvilaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago"}]},{"@type":"WebSite","@id":"https:\/\/www.salvilaw.com\/es\/#website","url":"https:\/\/www.salvilaw.com\/es\/","name":"Salvi, Schostok & Pritchard P.C.","description":"Your Illinois Medical Malpractice and Personal Injury Attorneys","publisher":{"@id":"https:\/\/www.salvilaw.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvilaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salvilaw.com\/es\/#\/schema\/person\/397e7f1c74e734538b0f150d958028a5","name":"Marcie Mangan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/49f3e28c3ddf4df894186e2a6efe70e49354e7b7dda983e7999dd99c2b41eb33?s=96&d=mm&r=g","caption":"Marcie Mangan"},"description":"Marcella R. Mangan is the Marketing and Public Relations Director of Salvi, Schostok &amp; Pritchard P.C., where she is primarily responsible for overseeing the firm\u2019s media strategy, events and managing the firm\u2019s website, social media pages and legal listings. She joined the firm in 2016\u00a0as the Public Relations Manager, was promoted to Public Relations Director in 2018, and was promoted again to Marketing and PR Director in 2020. During her time with the firm, Ms. Mangan has regularly booked attorneys for segments on local news stations and planned numerous press conferences that were covered by national media outlets. In addition, she serves as host of the firm\u2019s official podcast: Beating Goliath \u2013 A Plaintiff\u2019s Pursuit of Justice. Ms. Mangan graduated from Butler University with degrees in Journalism and Public Relations and a minor in Dance. Upon graduation, she spent four years working in Top 25 market newsrooms, including WISH-TV in Indianapolis and FOX 32 in Chicago. In these roles, she made on-air appearances, managed the station\u2019s social media platforms, wrote articles for their websites, and worked on the assignment desk. A native of the south suburbs, Ms. Mangan holds memberships in the Public Relations Society of America and the Publicity Club of Chicago. ACADEMICS B.A., Butler University\u00a0(2012)","url":"https:\/\/www.salvilaw.com\/es\/blog\/author\/mmangan\/"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/#local-main-organization-logo","url":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2018\/11\/logo.png","width":266,"height":108,"caption":"Salvi, Schostok & Pritchard P.C."}]},"geo.region":"Estados Unidos (EEUU)"},"modified_by":"Joan Quisay","parsely":{"version":"1.1.0","canonical_url":"https:\/\/salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuatro personas resultaron hospitalizadas, entre ellas un beb\u00e9, tras un accidente en el que se vio involucrada la polic\u00eda de Chicago","url":"http:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.salvilaw.com\/es\/blog\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\/"},"thumbnailUrl":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago-150x150.jpg","image":{"@type":"ImageObject","url":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2026\/05\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg"},"articleSection":"Noticias de accidentes","author":[{"@type":"Person","name":"Marcie Mangan"}],"creator":["Marcie Mangan"],"publisher":{"@type":"Organization","name":"Salvi, Schostok &amp; Pritchard P.C.","logo":"https:\/\/www.salvilaw.com\/wp-content\/uploads\/2018\/10\/SSP-favicon.png"},"keywords":[],"dateCreated":"2026-05-13T20:46:23Z","datePublished":"2026-05-13T20:46:23Z","dateModified":"2026-05-20T15:30:22Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuatro personas resultaron hospitalizadas, entre ellas un beb\\u00e9, tras un accidente en el que se vio involucrada la polic\\u00eda de Chicago\",\"url\":\"http:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.salvilaw.com\\\/es\\\/blog\\\/cuatro-hospitalizados-incluyendo-bebe-choque-involucrando-policia-chicago\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago-150x150.jpg\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Cuatro-personas-resultaron-hospitalizadas-entre-ellas-un-bebe-tras-un-accidente-en-el-que-se-vio-involucrada-la-policia-de-Chicago.jpg\"},\"articleSection\":\"Noticias de accidentes\",\"author\":[{\"@type\":\"Person\",\"name\":\"Marcie Mangan\"}],\"creator\":[\"Marcie Mangan\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Salvi, Schostok &amp; Pritchard P.C.\",\"logo\":\"https:\\\/\\\/www.salvilaw.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/SSP-favicon.png\"},\"keywords\":[],\"dateCreated\":\"2026-05-13T20:46:23Z\",\"datePublished\":\"2026-05-13T20:46:23Z\",\"dateModified\":\"2026-05-20T15:30:22Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/salvilaw.com\/p.js"},"_links":{"self":[{"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/posts\/2869484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/comments?post=2869484"}],"version-history":[{"count":0,"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/posts\/2869484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/media\/2869544"}],"wp:attachment":[{"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/media?parent=2869484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvilaw.com\/es\/wp-json\/wp\/v2\/categories?post=2869484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}